{"id":22098,"date":"2023-07-29T16:38:43","date_gmt":"2023-07-29T16:38:43","guid":{"rendered":"https:\/\/liberationinfo.com\/?p=22098"},"modified":"2023-07-29T16:39:44","modified_gmt":"2023-07-29T16:39:44","slug":"mmahawa-sidibe-met-fin-au-reve-de-grand-p-je-ne-veux-pas-de-grand-je-veux-un-homme-de-grand-de-taille","status":"publish","type":"post","link":"https:\/\/liberationinfo.com\/index.php\/mmahawa-sidibe-met-fin-au-reve-de-grand-p-je-ne-veux-pas-de-grand-je-veux-un-homme-de-grand-de-taille\/","title":{"rendered":"M\u2019Mahawa Sidib\u00e9 met fin au r\u00eave de Grand P : \u00ab Je ne veux pas de Grand P , je veux un homme grand de taille&#8230;\u00bb"},"content":{"rendered":"<p>Devenue la star du moment depuis son admission au baccalaur\u00e9at session 2022-2023, M&rsquo;Mahawa Sidib\u00e9 est activement pr\u00e9sente dans les m\u00e9dias et sur les r\u00e9seaux sociaux depuis la publication des derniers r\u00e9sultats.<\/p>\n<p>Au lendemain de la publication des r\u00e9sultats Grand P, qui est une autre rock Star en Guin\u00e9e et sur le continent, l&rsquo;a f\u00e9licit\u00e9 sur sa page Facebook et une publication qui a \u00e9t\u00e9 reprise par la jeune demoiselle Sidib\u00e9 sur son compte Facebook.<\/p>\n<p>Quelque chose qui a attir\u00e9 l&rsquo;attention de plusieurs guin\u00e9ens et qui ont pens\u00e9 un rapprochement entre les deux personnes. Dans une r\u00e9cente rencontre qu&rsquo;elle a eu avec le ministre de la justice et des droits de l\u2019Homme, Charles Alphonse Wringht, M\u2019Mahawa Sidib\u00e9 a \u00e9t\u00e9 interrog\u00e9e par la r\u00e9daction du site d&rsquo;informations le renifleur224.com.<\/p>\n<p>Elle a tranch\u00e9 : \u00ab <em><strong>Je ne me suis jamais vu avec Grand P et ce n\u2019est pas vrai, il n\u2019y a aucun projet de mariage entre nous<\/strong><\/em> \u00bb a-t-elle r\u00e9agi M\u2019Mahawa Sidib\u00e9, avant de donner sa donner le profil sur son futur \u00e9poux.<\/p>\n<p>\u00ab <em><strong>Je ne veux pas de Grand P, je m\u00e9rite plus que \u00e7a(rire). Je veux un homme, grand de taille et qu\u2019il soit ministre ou Pr\u00e9sident<\/strong><\/em> \u00bb a-t-elle\u00a0 laiss\u00e9 entendre.<\/p>\n<p>Une communication qui vient de mettre fin au r\u00eave de Grand P et son entourage pour un \u00e9ventuel mariage.<\/p>\n<p><strong>Liberationinfo.com<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Devenue la star du moment depuis son admission au baccalaur\u00e9at session 2022-2023, M&rsquo;Mahawa Sidib\u00e9 est activement pr\u00e9sente dans les m\u00e9dias et sur les r\u00e9seaux sociaux depuis la publication des derniers r\u00e9sultats. Au lendemain de la publication des r\u00e9sultats Grand P, qui est une autre rock Star en Guin\u00e9e et sur le continent, l&rsquo;a f\u00e9licit\u00e9 sur [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":22099,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4,6],"tags":[],"class_list":["post-22098","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actu","category-societe"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/liberationinfo.com\/wp-content\/uploads\/2023\/07\/IMG-20230729-WA0035.jpg?fit=1080%2C481&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/liberationinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/22098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/liberationinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/liberationinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/liberationinfo.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/liberationinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=22098"}],"version-history":[{"count":0,"href":"https:\/\/liberationinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/22098\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/liberationinfo.com\/index.php\/wp-json\/wp\/v2\/media\/22099"}],"wp:attachment":[{"href":"https:\/\/liberationinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=22098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/liberationinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=22098"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/liberationinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=22098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}