{"id":22029,"date":"2023-07-22T10:20:48","date_gmt":"2023-07-22T10:20:48","guid":{"rendered":"https:\/\/liberationinfo.com\/?p=22029"},"modified":"2023-07-22T10:20:48","modified_gmt":"2023-07-22T10:20:48","slug":"30-ans-sur-le-toit-de-la-guinee-tibou-kamara","status":"publish","type":"post","link":"https:\/\/liberationinfo.com\/index.php\/30-ans-sur-le-toit-de-la-guinee-tibou-kamara\/","title":{"rendered":"30 ans, sur le toit de la Guin\u00e9e (Tibou kamara)"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Le 15 septembre, prochain, Ibro Diabat\u00e9, l\u2019artiste du peuple, soufflera les 30 bougies de sa vie de cr\u00e9ateur, pav\u00e9e de succ\u00e8s dont il continue \u00e0 entretenir la flamme dans le ciel guin\u00e9en clair-obscur.<\/p>\n<p>Il n\u2019a pas d\u2019\u00e9gal encore dans sa g\u00e9n\u00e9ration car son immense \u0153uvre n\u2019a pas pris une seule ride et continue \u00e0 bercer tout le pays. Lui-m\u00eame, conserve l\u2019\u00e9nergie de la cr\u00e9ation et ne conna\u00eet pas le d\u00e9clin des ann\u00e9es d\u2019usure et de routine, \u00e0 une \u00e9poque o\u00f9 les talents \u00e9closent de partout, mine de rien, et bousculent l\u2019ordre \u00e9tabli, jadis.<\/p>\n<p>Jeune journaliste, passionn\u00e9 des \u0153uvres de g\u00e9nie, j\u2019ai suivi ses pas et, comme tant d\u2019autres, reste fascin\u00e9 par sa cr\u00e9ativit\u00e9 ph\u00e9nom\u00e9nale, subjugu\u00e9 par son inspiration intarissable, relevant du surnaturel.<\/p>\n<p>Il m\u2019a fait d\u00e9couvrir la vie de nuit de soir\u00e9es conviviales et f\u00e9eriques, et m\u2019a initi\u00e9 aux myst\u00e8res de la libert\u00e9 artistique d\u00e9fiante et incontr\u00f4lable. Pendant que le hasard me transportait sur le sentier sinueux de l\u2019engagement public avec toutes ses servitudes, son horizon artistique \u00e9tait \u00e0 son comble, plein de promesses. Partout, o\u00f9 il passait, il drainait des foules qui en ont fait un homme \u00e9cout\u00e9 et respect\u00e9, courtis\u00e9 aussi.<\/p>\n<p>Les \u00e9lus de Dieu, s\u2019imposent \u00e0 tous, et durent dans les m\u00e9moires.<br \/>\nLe trenti\u00e8me anniversaire de la carri\u00e8re de Ibro Diabat\u00e9 est un hymne \u00e0 une musique guin\u00e9enne qu\u2019il a contribu\u00e9e \u00e0 hisser tr\u00e8s haut, dont il est un des chantres vivants. L\u2019occasion est donn\u00e9e \u00e0 tous de revisiter le temps et de s\u2019attarder sur des pans oubli\u00e9s, des fresques marquantes.<\/p>\n<p>Ibro, n\u2019est pas qu\u2019un artiste qui fait de l\u2019art pour l\u2019art, il demeure une lumi\u00e8re qui traverse des c\u0153urs, agonisants; \u00e9claire des consciences endormies.<br \/>\nLe c\u00e9l\u00e8brer devant son public fid\u00e8le \u00e0 lui, fier de son parcours, est une \u00e9tape dans la reconnaissance \u00e9ternelle due \u00e0 tout homme qui d\u00e9die sa vie \u00e0 l\u2019art et fait le bonheur d\u2019anonymes dans les chaumi\u00e8res o\u00f9 derri\u00e8re les rideaux, beaucoup pleurent dans le silence, en attendant, toutes ces m\u00e9lodies, qui font tant de bien aux \u00e2mes en peine,<\/p>\n<p>Merci, Ibro de continuer \u00e0 nous rendre heureux, en nous apaisant par tes paroles d\u2019espoir, de sagesse, et d\u2019amour g\u00e9n\u00e9reux , par tes conseils avis\u00e9s. Tu nous rends si forts et meilleurs !<\/p>\n<p><strong>Tibou kamara<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Le 15 septembre, prochain, Ibro Diabat\u00e9, l\u2019artiste du peuple, soufflera les 30 bougies de sa vie de cr\u00e9ateur, pav\u00e9e de succ\u00e8s dont il continue \u00e0 entretenir la flamme dans le ciel guin\u00e9en clair-obscur. Il n\u2019a pas d\u2019\u00e9gal encore dans sa g\u00e9n\u00e9ration car son immense \u0153uvre n\u2019a pas pris une seule ride et continue \u00e0 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":22030,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[8],"tags":[],"class_list":["post-22029","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-culture"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/liberationinfo.com\/wp-content\/uploads\/2023\/07\/IMG-20230722-WA0017.jpg?fit=800%2C504&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/liberationinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/22029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/liberationinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/liberationinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/liberationinfo.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/liberationinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=22029"}],"version-history":[{"count":0,"href":"https:\/\/liberationinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/22029\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/liberationinfo.com\/index.php\/wp-json\/wp\/v2\/media\/22030"}],"wp:attachment":[{"href":"https:\/\/liberationinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=22029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/liberationinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=22029"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/liberationinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=22029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}